{"id":1417,"date":"2013-02-05T05:11:16","date_gmt":"2013-02-05T04:11:16","guid":{"rendered":"http:\/\/www.hexence.com\/gnupick\/?p=1417"},"modified":"2013-05-16T01:29:55","modified_gmt":"2013-05-15T23:29:55","slug":"quantumnauts-chapter-1-speed-of-light-space-pirates-and-multiverses","status":"publish","type":"post","link":"https:\/\/www.hexence.com\/gnupick\/quantumnauts-chapter-1-speed-of-light-space-pirates-and-multiverses\/","title":{"rendered":"Quantumnauts \u2013 Chapter 1: Speed of Light, Space Pirates and Multiverses"},"content":{"rendered":"<p><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/COPERTINA-GIOCO-QUANTUMNAUTS.jpg\" target=\"_blank\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft  wp-image-1418\" title=\"Quantumnauts_cover\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/COPERTINA-GIOCO-QUANTUMNAUTS-263x300.jpg\" alt=\"\" width=\"200\" height=\"227\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/COPERTINA-GIOCO-QUANTUMNAUTS-263x300.jpg 263w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/COPERTINA-GIOCO-QUANTUMNAUTS.jpg 527w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/a>Il giovane Bob Marshall, musicista in una band heavy metal, si trascina a casa barcollante in seguito a un concerto e all\u2019immancabile bevuta. All\u2019improvviso il suo corpo viene teletrasportato all\u2019interno di una nave spaziale: l\u2019occupante, che si identifica come un viaggiatore dei multiversi \u2013 un \u2018Quantumnauta\u2019 -, chiarisce che \u00e8 l\u00ec a causa di un madornale errore di coordinate: neanche il tempo di rimediare allo sbaglio e di portare a bordo il vero capitano, che l\u2019astronave viene attaccata dai pirati spaziali e, in completa avaria, finisce su un mondo del tredicesimo universo. Dopo aver osservato il decesso del Quantumnauta, a Bob non resta che rubare la sua identit\u00e0 ed esplorare il pianeta in cerca di un modo per tornare a casa. Scoprir\u00e0 un sistema politico dittatoriale contrastato da un pugno di ribelli in cui milita la giovane e ovviamente bellissima Neena. <!--more--><\/p>\n<div id=\"attachment_1419\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/1.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-1419\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1419  \" title=\"Quantumnauts_1\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/1-300x225.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/1.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1419\" class=\"wp-caption-text\">L&#39;assenza di ombre realistiche proiettate dai personaggi e l&#39;inadeguato sistema di illuminazione non permettono una realistica &#39;fusione&#39; dei vari elementi.<\/p><\/div>\n<p>\u201c<strong>Quantumnauts \u2013 Chapter 1<\/strong>\u201d (2010) rappresenta l\u2019ingresso nel mondo delle avventure commerciali da parte della <em>Midian Design<\/em> (dietro cui si cela un unico sviluppatore, <strong><em>Danilo Cagliari<\/em><\/strong>), gi\u00e0 responsabile dell\u2019umoristico freeware \u201c<strong>J.J. Gun e l\u2019Isola di Sepheret<\/strong>\u201d.<br \/>\nDurante i primi minuti si pu\u00f2 osservare come il gioco paghi lo scotto di uno sviluppo affrettato, a cominciare dalla generale pochezza grafica (scarsezza di animazioni, assenza di ombre complesse, location spoglie) fino ad arrivare a una certa mancanza di rifiniture (inventario pesante, qualche interazione nulla). \u00c8 possibile chiudere un occhio di fronte a tali magagne se si tiene conto del team di sviluppo ridotto a una sola unit\u00e0, della scelta dell\u2019engine (il gratuito <em>Adventure Game Studio<\/em>) e del prezzo davvero contenuto, ma \u00e8 anche giusto constatare che i suddetti limiti sono stati gestiti decisamente meglio in altre occasioni (come nel caso dei titoli <em>Wadjet Eye<\/em>).<\/p>\n<div id=\"attachment_1420\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/2.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-1420\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1420 \" title=\"Quantumnauts_2\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/2-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/2-300x225.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/2.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1420\" class=\"wp-caption-text\">Questo mercante acquista un po&#39; di tutto, e far\u00e0 guadagnare a Bob un bel gruzzoletto. Sulla sinistra \u00e8 possibile scorgere uno dei tanti riferimenti ai classici della fantascienza.<\/p><\/div>\n<p>Proseguendo nell\u2019avventura \u00e8 per\u00f2 possibile farsi un\u2019idea pi\u00f9 precisa riguardo agli intenti dell\u2019autore: \u201cQuantumnauts\u201d sembra infatti un titolo dalle ambizioni non elevatissime, una sorta di test sul campo in vista di progetti pi\u00f9 complessi. La scarsa longevit\u00e0 conferma tale ipotesi e probabilmente il desiderio di ricevere del feedback il pi\u00f9 presto possibile.<br \/>\nQuella che sembra una scusante rappresenta in realt\u00e0 un onesto banco di prova per l\u2019autore, evidentemente desideroso di migliorare in vista di progetti futuri.<\/p>\n<p>Non \u00e8 quindi una sorpresa se l\u2019avventura si presenta accessibile grazie al tono leggero e scanzonato, pieno zeppo di citazioni sci-fi e strizzate d\u2019occhio agli oldgamer. Nonostante una cura forse eccessiva circa il background relativo alla situazione sociale del pianeta (in fin dei conti piuttosto superfluo), \u201cQuantumnauts\u201d si accontenta infatti di essere piacevole grazie a enigmi quasi sempre logici, a qualche situazione comica o surreale e all\u2019irriverenza del protagonista (una via di mezzo fra il Jack di \u201c<a href=\"http:\/\/www.hexence.com\/gnupick\/innocent-until-caught\/\" target=\"_blank\"><strong>Innocent Until Caught<\/strong><\/a>\u201d e \u201c<a href=\"http:\/\/www.hexence.com\/gnupick\/simon-the-sorcerer\/\" target=\"_blank\"><strong>Simon the Sorcerer<\/strong><\/a>\u201d).<\/p>\n<div id=\"attachment_1421\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/3.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-1421\" decoding=\"async\" loading=\"lazy\" class=\" wp-image-1421 \" title=\"Quantumnauts_3\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/3-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/3-300x225.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/3.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1421\" class=\"wp-caption-text\">L&#39;enigma in questa locazione \u00e8 uno dei pi\u00f9 ostici, e in situazioni come queste la lentezza del &#39;walk&#39; del protagonista diventa un difetto rilevante.<\/p><\/div>\n<p>Bench\u00e9 non faccia ribaltare dalla sedia, l\u2019umorismo adottato si rivela gustoso in diverse occasioni e, pi\u00f9 in generale, l\u2019intero prodotto \u00e8 permeato di quel rilassante profumo <em>old school<\/em> che favorisce senza dubbio la giocabilit\u00e0.<br \/>\nPollice verso per le musiche, incomprensibilmente sparate a un volume folle e fin troppo invadenti; assenti doppiaggio ed effetti sonori.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"attachment_1422\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/4.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-1422\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1422 \" title=\"Quantumnauts_4\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/4-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/4-300x225.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/02\/4.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1422\" class=\"wp-caption-text\">La giovane Neena, per gran parte del tempo, seguir\u00e0 il nostro Bob in forma &#39;incorporea&#39;.<\/p><\/div>\n<p>\u201c<strong>Quantumnauts &#8211; Chapter 1<\/strong>\u201d \u00e8 un primo tentativo sicuramente perfettibile, ma l\u2019umilt\u00e0 dell\u2019autore italiano fornisce un\u2019ottima base in vista di futuri miglioramenti.<br \/>\n{rating}<\/p>\n<p><strong>La citazione<\/strong>:<br \/>\nBob: (osservando delle incisioni) C\u2019\u00e8 l\u2019Esercito Ombra che combatte contro un altro popolo, delle astronavi a forma di polipo nel cielo\u2026 C\u2019\u00e8 anche una figura che ricorda Neena, quei capelli pu\u00f2 averli solo lei. C\u2019\u00e8 anche un tizio con una faccia davvero stupida.<br \/>\nBob: Hey!! Ma quello sono io.<br \/>\nBob: Avevo visto male, \u00e8 davvero un tipo interessante, portamento da condottiero e sguardo fiero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il giovane Bob Marshall, musicista in una band heavy metal, si trascina a casa barcollante in seguito a un concerto e all\u2019immancabile bevuta. All\u2019improvviso il suo corpo viene teletrasportato all\u2019interno di una nave spaziale: l\u2019occupante, che si identifica come un viaggiatore dei multiversi \u2013 un \u2018Quantumnauta\u2019 -, chiarisce che \u00e8 l\u00ec a causa di un madornale errore di coordinate: neanche &hellip;<span class=\"more-link\"><a href=\"https:\/\/www.hexence.com\/gnupick\/quantumnauts-chapter-1-speed-of-light-space-pirates-and-multiverses\/\"><span class=\"button\"><b>Continua a leggere &rarr;<\/b><\/span><\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/1417"}],"collection":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/comments?post=1417"}],"version-history":[{"count":8,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/1417\/revisions"}],"predecessor-version":[{"id":1442,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/1417\/revisions\/1442"}],"wp:attachment":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/media?parent=1417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/categories?post=1417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/tags?post=1417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}