{"id":1550,"date":"2013-05-27T03:31:15","date_gmt":"2013-05-27T01:31:15","guid":{"rendered":"http:\/\/www.hexence.com\/gnupick\/?p=1550"},"modified":"2021-10-01T02:48:58","modified_gmt":"2021-10-01T00:48:58","slug":"dune","status":"publish","type":"post","link":"https:\/\/www.hexence.com\/gnupick\/dune\/","title":{"rendered":"Dune"},"content":{"rendered":"<p><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_0big.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft  wp-image-1551\" title=\"Dune_cover\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_0big-226x300.jpg\" alt=\"\" width=\"213\" height=\"275\" \/><\/a>Il mondo di \u201cDune\u201d, partorito dal genio dello scrittore Frank Herbert dal 1965, \u00e8 uno degli universi fantastici pi\u00f9 dettagliati e apprezzati di tutti i tempi. La miscela unica di fantascienza, misticismo ed ecologia, l\u2019ha reso un mondo realmente pulsante caratterizzato da un\u2019incredibile cura per i dettagli.<br \/>\nIl primo libro \u00e8 stato poi seguito da altri cinque tomi scritti dall\u2019autore originale e, solo di recente, Brian Herbert (figlio di Frank) e Kevin J. Anderson (dopo aver gi\u00e0 elaborato dei prequel) hanno chiuso la saga\u00a0con l\u2019ultimo capitolo, il numero sette.<br \/>\nIl primo libro, \u201cDune\u201d, resta comunque il pi\u00f9 significativo e famoso, un\u2019opera unica capace di ispirare anche i pi\u00f9 grandi narratori moderni (come, per sua stessa ammissione, il George Lucas di \u201cStar Wars\u201d).<br \/>\nMolto difficile appariva una trasposizione cinematografica che ne conservasse lo spirito e, soprattutto, la ricchezza e la mirabolante complessit\u00e0 della trama, descritta attraverso personaggi profondamente caratterizzati che si muovono tra mille avversit\u00e0 in un mondo ostile, laddove il vero pericolo non deriva dal terrorizzante Verme gigante delle sabbie, bens\u00ec dall\u2019avidit\u00e0 e dalla smania di potere dell\u2019essere umano, capace di escogitare \u2018piani dentro ai piani\u2019, impensabili trame e sottotrame di natura politica e, addirittura, manipolazioni genetiche sulle nascite.<!--more--><\/p>\n<div id=\"attachment_1561\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_10big.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img aria-describedby=\"caption-attachment-1561\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1561 \" title=\"Dune_1\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_10big-300x188.jpg\" alt=\"\" width=\"300\" height=\"188\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_10big-300x188.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_10big-1024x642.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_10big.jpg 1279w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1561\" class=\"wp-caption-text\">Nostro padre, Leto Atreides, ci sprona a prendere in mano il destino in continuo mutamento.<\/p><\/div>\n<p>L\u2019arduo compito fu tentato dal regista di culto David Lynch nel 1984, con un lungometraggio tormentato e a suo modo intriso di atmosfera, ma troppo \u2018libero\u2019 e discutibile nell\u2019adattamento.<br \/>\nCi riprov\u00f2 la tv, con il regista John Harrison e la discreta miniserie del 2000 \u201cFrank Herbert\u2019s: Dune\u201d (in italiano \u00e8 \u201cDune: Il Destino dell\u2019Universo\u201d): la durata di circa quattro ore e mezzo riusciva a presentare una versione ben pi\u00f9 coerente allo scritto originale, anche se un po\u2019 carente di personalit\u00e0. Alla prima miniserie ne \u00e8 poi seguita un\u2019altra, l\u2019eccezionale \u201cFrank Herbert\u2019s: Children of Dune\u201d (basata su \u201cMessia di Dune\u201d e \u201cI Figli di Dune\u201d, rispettivamente il secondo e il terzo libro della saga) di Greg Yaitanes e sceneggiata dallo stesso Harrison: una versione filmica di grande impatto, finalmente degna di rappresentare l\u2019universo di Herbert.<\/p>\n<div id=\"attachment_1552\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_1big.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img aria-describedby=\"caption-attachment-1552\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1552 \" title=\"Dune_2\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_1big-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_1big-300x187.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_1big-1024x640.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_1big.jpg 1281w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1552\" class=\"wp-caption-text\">Attraverso questa visuale, conosceremo le statistiche della guerra. Gli Harkonnen sono segnalati con il colore blu, gli Atreides il rosso. Come dimostra l&#8217;immagine, c&#8217;\u00e8 ancora molto da lavorare!<\/p><\/div>\n<p>L\u2019universo videoludico non si \u00e8 mai fatto pregare di \u2018tradurre\u2019 elettronicamente il mondo di \u201cDune\u201d, e a oggi sono diversi i titoli che \u2013 con risultati altalenanti &#8211; hanno sfruttato il marchio.<br \/>\nLa neonata <em>Cryo Interactive<\/em>, nel 1992, fu incaricata dalla <em>Virgin Games<\/em> di realizzare la prima trasposizione videoludica del romanzo originale, ma fu sollevata dall\u2019incarico dopo poco in favore dei <em>Westwood Studios<\/em>, che avrebbero creato il memorabile strategico in real-time (il primo!) \u201c<strong>Dune II: Battle for Arrakis<\/strong>\u201d, senza dubbio uno dei pi\u00f9 influenti titoli della storia.<br \/>\nCi\u00f2 che la produzione non sapeva era che la <em>Cryo<\/em>, con a capo <strong><em>R\u00e9mi Herbulot<\/em><\/strong> (anche co-fondatore della \u00a0software house), continu\u00f2 in gran segreto a lavorare al proprio gioco fino a presentare a sorpresa il prodotto finale, al quale la <em>Virgin<\/em> (per fortuna!) non rinunci\u00f2, pubblicandolo ugualmente. Questo \u00e8 il motivo per cui i due giochi furono editi quasi contemporaneamente, ed ecco perch\u00e9 lo strategico della <em>Westwood<\/em> porta il numero \u201cII\u201d nel titolo pur non avendo niente a che vedere con l\u2019avventura della <em>Cryo<\/em> (a parte lo sfruttamento dell\u2019ambientazione, \u201cDune II\u201d \u00e8 infatti una versione alternativa della storia originale).<\/p>\n<div id=\"attachment_1553\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_2big.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img aria-describedby=\"caption-attachment-1553\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1553 \" title=\"Dune_3\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_2big-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_2big-300x187.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_2big-1024x639.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_2big.jpg 1279w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1553\" class=\"wp-caption-text\">Chani non \u00e8 di certo una ragazza che ama i giri di parole. Ci buttiamo? Ma s\u00ec, d&#8217;altra parte Leto diceva &#8220;Il DORMIENTE deve essere svegliato&#8221;!<\/p><\/div>\n<p>Torniamo al titolo in oggetto.<br \/>\nIl gameplay di \u201c<strong>Dune<\/strong>\u201d \u00e8 ibrido: un\u2019avventura grafica con pesantissime influenze strategiche e perfino un pizzico di gioco di ruolo. Appare frutto di una singolare mescolanza anche riguardo alle ispirazioni narrative: la storia pu\u00f2 definirsi infatti una via di mezzo fra il romanzo e il film di Lynch dell\u201984, con l\u2019aggiunta di grosse ed evidenti licenze per poter funzionare sottoforma di videogioco.<\/p>\n<p>Si impersona Paul, giovane rampollo degli Atreides in trasferta sul pianeta Arrakis &#8211; conosciuto anche come Dune &#8211; con un\u2019importante missione: collaborare con i misteriosi nativi, i Fremen, per estrarre la Spezia, la sostanza pi\u00f9 preziosa dell\u2019universo grazie alla quale si rendono possibili i viaggi interplanetari.<br \/>\nEsiste per\u00f2 un grosso problema. L\u2019imperatore Shaddam IV, che ha \u2018invitato\u2019 la casa Atreides a incrementare l\u2019estrazione della Spezia, pretende periodicamente l\u2019invio \u2013 sempre maggiore &#8211; del prezioso materiale. Ci\u00f2 che \u00e8 peggio \u00e8 che il pianeta \u00e8 controllato anche dagli storici nemici degli Atreides, i malvagi Harkonnen, con a capo il grasso Barone e il nipote Feyd-Rautha, decisi a scacciare Paul e famiglia da Arrakis con ogni mezzo lecito o illecito.<br \/>\nPer fronteggiare una tale minaccia in un pianeta alieno gi\u00e0 di per s\u00e9 ostile (oltre ai giganti Vermi della sabbia che attaccano le mietitrici di Spezia, sul pianeta non c\u2019\u00e8 una sola goccia d\u2019acqua e i Fremen sono poco disposti a concedere un aiuto), Paul potr\u00e0 contare su suo padre, il nobile Duca Leto Atreides, la madre Jessica, che gli ha impartito il difficile insegnamento Bene Gesserit, l\u2019amico Duncan Idaho, consulente economico, Gurney Halleck, esperto maestro d\u2019armi, e il Mentat (computer umano) Thufir Hawat.<br \/>\nDurante il suo viaggio, Paul dovr\u00e0 dapprima stabilizzare la produzione di Spezia grazie a un gran numero di alleati Fremen e, in seguito, dovr\u00e0 creare con essi un vero e proprio esercito militare in grado di affrontare gli Harkonnen fortezza dopo fortezza, fino ad arrivare alla loro roccaforte principale. Nel frattempo conoscer\u00e0 il saggio combattente Stilgar, capo dei Fremen, e la seducente Chani, figlia di Liet Kynes, un ecologo che promette di cambiar faccia al pianeta e di trasformarlo in un grande giardino lussureggiante.<\/p>\n<div id=\"attachment_1554\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_3big.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img aria-describedby=\"caption-attachment-1554\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1554 \" title=\"Dune_4\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_3big-300x142.jpg\" alt=\"\" width=\"300\" height=\"142\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_3big-300x142.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_3big-1024x486.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_3big.jpg 1279w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1554\" class=\"wp-caption-text\">Il gigantesco Verme delle sabbie costituir\u00e0 un problema per molto tempo, ma i Fremen ci insegneranno ad usare la sua possanza a nostro favore.<\/p><\/div>\n<p>La prima parte del gioco \u00e8 quindi costituita da una generale esplorazione di Arrakis in cerca di \u2018sietch\u2019 (caverne Fremen) da occupare per far partire la produzione di Spezia. Mietitrici (indispensabili per incrementare l\u2019estrazione) e ornitotteri (utili per sollevare la mietitrice durante l\u2019attacco di un Verme) sono recuperabili all\u2019esterno di particolari sietch o attraverso contrabbandieri nascosti e diventano presto indispensabili per garantire un apporto di Spezia continuo. Durante questa sezione di raccolta, solo parzialmente strategica, si affronta contemporaneamente un percorso \u2018adventure\u2019 molto semplice che fa da collante alle varie vicende della trama (ovviamente \u2018molto\u2019 banalizzata rispetto al romanzo e al film di Lynch).<br \/>\nDa un certo punto in poi, per\u00f2, gli Harkonnen cominceranno ad attaccare i nostri sietch, e sar\u00e0 quindi necessario passare al contrattacco: esortando i Fremen a cominciare un addestramento militare, si recluteranno infatti le forze necessarie per affrontare i brutali rivali. \u00c8 qui che il gioco si trasforma quasi esclusivamente in uno strategico, lasciando al giocatore il compito di organizzare le truppe, recuperare armi (fra cui anche i \u2018moduli estranianti\u2019, assenti nel romanzo ma presi di peso dal film di Lynch) e attaccare fortezze nemiche, mentre la parte \u2018adventure\u2019 verr\u00e0 un po\u2019 meno, bench\u00e9 siano presenti sporadiche evoluzioni nella storia.<br \/>\nNon manca anche una crescita stile gdr: col tempo, non solo i Fremen diventeranno sempre pi\u00f9 abili, ma lo stesso Paul acquisir\u00e0 poteri particolari, fra cui la veggenza e la capacit\u00e0 di comunicare a grande distanza solo col pensiero.<br \/>\nPer finire, grazie all\u2019aiuto del padre di Chani, sar\u00e0 anche possibile addestrare le truppe come ecologi, in modo da far crescere delle piante sul suolo desertico di Arrakis: ci\u00f2 porter\u00e0 a una riduzione progressiva della Spezia nelle aree \u2018colpite\u2019, da usare come inusuale arma contro gli avidi Harkonnen.<\/p>\n<div id=\"attachment_1555\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_4big.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img aria-describedby=\"caption-attachment-1555\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1555 \" title=\"Dune_5\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_4big-300x177.jpg\" alt=\"\" width=\"300\" height=\"177\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_4big-300x177.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_4big-1024x604.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_4big.jpg 1279w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1555\" class=\"wp-caption-text\">L&#8217;attore Kyle MacLachlan \u00e8 l&#8217;unico a prestare il suo volto sia alla versione digitale di Paul che ai video tratti dal film.<\/p><\/div>\n<p>L\u2019aspetto pi\u00f9 interessante di \u201cDune\u201d \u00e8, come prevedibile, quello strategico. Anche se curiosamente sembra anticipare qualche intuizione del \u2018seguito\u2019 della <em>Westwood<\/em> (il tempo di gioco \u00e8 parzialmente reale, con tanto di alternarsi giorno\/notte), non possiede l\u2019eccezionale esplosione di giocabilit\u00e0 del suddetto capolavoro pionieristico. Nonostante ci\u00f2, restano molti punti degni di nota, fra cui una discreta variet\u00e0 (caratterizzata dai tre diversi \u2018lavori\u2019 delle truppe: estrazione Spezia, combattimento, ecologia), a cui si associa la necessit\u00e0 di coordinare contemporaneamente un esercito per avere una qualche speranza contro gli Harkonnen.<br \/>\nIl \u2018cuore\u2019 resta comunque la parte militare, non molto complessa in s\u00e9 (bench\u00e9 sia disponibile un\u2019interessante funzione di \u2018spionaggio\u2019), ma che richiede non solo particolare attenzione nel gestire le truppe giuste, ma anche una ricerca minuziosa degli armamenti adatti (che culminano con le atomiche, indispensabili durante gli ultimi attacchi) e un\u2019adeguata esperienza dei nostri Fremen per affrontare gli scontri pi\u00f9 duri. La presenza di Paul durante un combattimento incerto, inoltre, \u00e8 capace di risollevare il morale dei suoi uomini e condurre lo scontro verso un esito favorevole. Naturalmente, rischi come questi andranno valutati accuratamente, pena la morte nel caso di sconfitta.<br \/>\nTale caso non rappresenta l\u2019unico modo\u00a0 per assistere al \u2018game over\u2019, comunque: addentrarsi nel deserto senza le tute distillanti Fremen pu\u00f2 rivelarsi fatale, cos\u00ec come volare sopra le fortezze Harkonnen o non pagare la frequente tassa di Spezia all\u2019Imperatore (il mancato adempimento di questo dovere scatener\u00e0 il suo imbattibile esercito di Sardaukar contro Paul).<\/p>\n<div id=\"attachment_1556\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_5big.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img aria-describedby=\"caption-attachment-1556\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1556 \" title=\"Dune_6\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_5big-300x188.jpg\" alt=\"\" width=\"300\" height=\"188\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_5big-300x188.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_5big-1024x642.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_5big.jpg 1279w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1556\" class=\"wp-caption-text\">Le spettacolari immagini delle battaglie fra Atreides e Harkonnen si ispirano alle riprese ad infrarossi utilizzate durante la Guerra del Golfo.<\/p><\/div>\n<p>Il fattore gdr \u00e8 invece solo abbozzato, bench\u00e9 determinante. I \u2018poteri\u2019 telepatici del rampollo Atreides (facolt\u00e0 utilissima per gestire le truppe su tutto il pianeta) si acquisiscono col tempo grazie all\u2019aumento del carisma esercitato sui Fremen (dipendente dall\u2019ammontare delle di truppe che il giocatore assolder\u00e0), che infine permetter\u00e0 di bere l\u2019Acqua della Vita, il misterioso liquido prodotto dai Vermi che consente di espandere le percezioni.<br \/>\nGrossa rilevanza \u00e8 data dall\u2019esperienza dei nostri Fremen, migliorabile solo con un intenso allenamento (in campo militare, la presenza di Gurney Halleck fra loro accelerer\u00e0 il processo).<\/p>\n<p>Altrettanto rilevante &#8211; ma pi\u00f9 presente &#8211; la componente adventure, che racconta la trama (adattata) del romanzo originale. In realt\u00e0, essendo l\u2019inventario del tutto assente, non c\u2019\u00e8 molto da fare a parte parlare con la persona giusta al momento giusto, seguendo le vicende con un certo distacco (e la visuale in prima persona con protagonista muto non aiuta). \u00c8 possibile anche chiedere la compagnia di un paio di personaggi non giocanti per poter usufruire di alcuni suggerimenti, facolt\u00e0, o anche solo per lasciare che la loro presenza porti avanti la storia.<\/p>\n<div id=\"attachment_1557\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_6big.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img aria-describedby=\"caption-attachment-1557\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1557 \" title=\"Dune_7\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_6big-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_6big-300x187.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_6big-1024x640.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_6big.jpg 1279w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1557\" class=\"wp-caption-text\">Durante il gioco, Paul ricever\u00e0 automaticamente delle comunicazioni attraverso le visioni.<\/p><\/div>\n<p>La trama ipersemplificata (molti sono gli eventi e i personaggi rimossi o adattati) e l\u2019assenza di qualsiasi approfondimento psicologico degno di questo nome sembrano condannare \u201cDune\u201d a essere un tie-in poco ispirato. Nonostante questo, per\u00f2, l\u2019imbattibile essenza herbertiana \u00e8 trasposta con buona riuscita, cos\u00ec come un discreto numero di suggestioni derivanti dal suo universo. Il risultato \u00e8 un titolo che in parte cattura con successo l\u2019atmosfera della saga, dimostrandosi notevole in tal senso pi\u00f9 per meriti dell\u2019ambientazione che per la qualit\u00e0 del gioco in s\u00e9, che comunque sfoggia una grafica convincente (quasi esaltante ai tempi dell\u2019uscita) e una colonna sonora a suo modo memorabile, composta da Stephane Picq e dal game designer e co-fondatore <em>Cryo<\/em> Philippe Ulrich. Particolarmente coerente col contesto, la partitura (musica elettronica <em>ambient<\/em> con un azzeccato utilizzo di percussioni) ha avuto l\u2019onore di essere pubblicata a parte (col titolo di \u201cDune: Spice Opera\u201d), divenendo uno dei pi\u00f9 venduti album di sempre tratto da un videogioco.<br \/>\nIn ogni caso, il gameplay ibrido semi-sperimentale appare a tratti zoppicante (specie nei momenti \u2018adventure\u2019) ma si pu\u00f2 dire che sia complessivamente stimolante nella sua variet\u00e0 (tanto da essere riproposto dagli autori in modo pressocch\u00e9 uguale nel blando clone \u201cLost Eden\u201d).<br \/>\nAiutata fortissimamente dalla bont\u00e0 della fonte ispiratrice, l\u2019atmosfera si fa epica nelle battute finali, bench\u00e9 l\u2019ending sia decisamente affrettato.<\/p>\n<div id=\"attachment_1558\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_7big.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img aria-describedby=\"caption-attachment-1558\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1558 \" title=\"Dune_6\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_7big-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_7big-300x187.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_7big-1024x639.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_7big.jpg 1278w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1558\" class=\"wp-caption-text\">Attraverso una funzione particolare, \u00e8 possibile accedere a una sorta di &#8216;sintesi&#8217; della storia narrata dalla principessa Irulan, erede al trono imperiale.<\/p><\/div>\n<p>Il \u2018trucco\u2019 nel portare a termine il gioco con successo sta soprattutto nell\u2019abilit\u00e0 del giocatore di velocizzare i tempi &#8211; evitando cos\u00ec di dar modo ai rivali di cominciare ad attaccare i nostri sietch &#8211; e organizzando un solido esercito militare mettendo il pi\u00f9 presto possibile da parte il problema dell\u2019estrazione di Spezia. Fondamentalmente inutile si rivela l\u2019aspetto ecologico, un\u2019arma a doppio taglio che pu\u00f2 ritorcersi contro (se gli Harkonnen soffrono di carenza di spezia, dopo aver conquistato le loro fortezze si avr\u00e0 lo stesso problema): molto migliore si rivela quindi la scelta di privilegiare l\u2019aspetto militare.<br \/>\nAttenzione per\u00f2 al numero di \u2018slot\u2019 di salvataggio, appena due, che costringe a un oculato utilizzo nei momenti di difficolt\u00e0.<\/p>\n<div id=\"attachment_1559\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_8big.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img aria-describedby=\"caption-attachment-1559\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1559 \" title=\"Dune_7\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_8big-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_8big-300x187.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_8big-1024x640.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_8big.jpg 1281w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1559\" class=\"wp-caption-text\">Questa volta \u00e8 andata male: morire di sete nel deserto \u00e8 senza dubbio una fine orribile.<\/p><\/div>\n<p>Decisamente non perfetta la difficile traduzione in italiano, non sempre coerente con il romanzo e spesso indecisa su alcuni termini (le tute vengono dette prima \u2018distillanti\u2019 poi \u2018distillatrici\u2019, i \u2018sietch\u2019 vengono chiamati troppo comunemente \u2018caverne\u2019). Presente anche qualche errore qua e l\u00e0.<\/p>\n<p>Una versione potenziata del gioco su CD (una delle primissime trasposizioni su supporto ottico) fu resa disponibile l\u2019anno successivo all\u2019uscita dell\u2019originale: l\u2019edizione aggiunge il parlato completo, musiche rielaborate, diversi filmati in 3D prerenderizzato al posto delle transizioni pi\u00f9 scarne della versione floppy (ancora oggi di ottima resa), e una serie di video direttamente presi dal film di Lynch (purtroppo trasposti con infima qualit\u00e0 per venire incontro ai PC del \u201993).<\/p>\n<div id=\"attachment_1560\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_9big.jpg\" target=\"_blank\" rel=\"noopener noreferrer\"><img aria-describedby=\"caption-attachment-1560\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1560 \" title=\"Dune_8\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_9big-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_9big-300x187.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_9big-1024x641.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2013\/05\/Dune_9big.jpg 1279w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1560\" class=\"wp-caption-text\">Attraverso la mappa \u00e8 possibile organizzare le nostre truppe. \u00c8 bene essere pronti a gestirla con efficienza, oppure non si avr\u00e0 scampo.<\/p><\/div>\n<p>Primo titolo sviluppato dalla <em>Cryo<\/em>, \u201c<strong>Dune<\/strong>\u201d pu\u00f2, nonostante tutto, considerarsi un ottimo inizio per la casa francese. Il gioco possiede certamente il merito di aver avvicinato i pi\u00f9 giovani all\u2019affascinante mondo di Herbert e di essere riuscito a trasporre con una certa qualit\u00e0 uno degli universi fantascientifici pi\u00f9 elaborati della storia.<br \/>\n{rating}<\/p>\n<p><strong>La citazione<\/strong>:<br \/>\nStilgar: Riunendo le nostre forze, saremo in grado di fermare gli Harkonnen. Ti chiameremo \u2018Muad\u2019Dib\u2019, il nome del topo canguro che si pu\u00f2 vedere sulla seconda luna di Dune. La tua acqua si mescoler\u00e0 alla nostra acqua!<\/p>\n<p><span style=\"text-decoration: underline;\">Nota<\/span>: Una straordinaria guida in italiano \u00e8 disponibile sul sito <a href=\"http:\/\/rymoahdunespot.altervista.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">Rymoah\u2019s Dune Spot<\/a>, completa di walkthrough, suggerimenti, trucchi, curiosit\u00e0 e perfino di una lista su come \u2018attivare\u2019 i bug presenti (curiosi ma non molto fastidiosi).<br \/>\nIl gioco possiede la licenza di utilizzare il marchio di \u201cDune\u201d e l\u2019immagine dell\u2019attore Kyle MacLachlan (Paul Atreides) direttamente dal film di David Lynch.<br \/>\nNessun problema a girare sui PC moderni a risoluzioni molto alte, a patto che si usi <a href=\"http:\/\/www.dosbox.com\/\">DOSBox<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il mondo di \u201cDune\u201d, partorito dal genio dello scrittore Frank Herbert dal 1965, \u00e8 uno degli universi fantastici pi\u00f9 dettagliati e apprezzati di tutti i tempi. La miscela unica di fantascienza, misticismo ed ecologia, l\u2019ha reso un mondo realmente pulsante caratterizzato da un\u2019incredibile cura per i dettagli. Il primo libro \u00e8 stato poi seguito da altri cinque tomi scritti dall\u2019autore &hellip;<span class=\"more-link\"><a href=\"https:\/\/www.hexence.com\/gnupick\/dune\/\"><span class=\"button\"><b>Continua a leggere &rarr;<\/b><\/span><\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/1550"}],"collection":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/comments?post=1550"}],"version-history":[{"count":12,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/1550\/revisions"}],"predecessor-version":[{"id":2691,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/1550\/revisions\/2691"}],"wp:attachment":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/media?parent=1550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/categories?post=1550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/tags?post=1550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}