{"id":628,"date":"2012-07-21T18:53:06","date_gmt":"2012-07-21T16:53:06","guid":{"rendered":"http:\/\/www.hexence.com\/gnupick\/?p=628"},"modified":"2013-01-29T02:58:43","modified_gmt":"2013-01-29T01:58:43","slug":"a-new-beginning","status":"publish","type":"post","link":"https:\/\/www.hexence.com\/gnupick\/a-new-beginning\/","title":{"rendered":"A New Beginning"},"content":{"rendered":"<p><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/cover.jpg\" target=\"_blank\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft  wp-image-633\" title=\"ANB_cover\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/cover-214x300.jpg\" alt=\"\" width=\"197\" height=\"275\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/cover-214x300.jpg 214w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/cover.jpg 640w\" sizes=\"(max-width: 197px) 100vw, 197px\" \/><\/a>In un futuro devastato da una serie di catastrofi ecologiche, una squadra viene invitata indietro nel tempo per fermare lo scoppio di una centrale nucleare in Brasile, responsabile di una terribile reazione a catena che porter\u00e0 al disastro climatico. Ben presto l\u2019intera missione finisce per dipendere dalla giovane radio-operatrice Fay e da Bent Svensson, uno scienziato del passato che ha ideato una nuova forma di energia pulita capace di soppiantare qualsiasi alternativa e porre fine alla minaccia. Il carattere burbero e demotivato di Bent e l\u2019appassionato idealismo di Fay si confronteranno a lungo prima che i due uniscano le forze contro un nemico comune, un magnate senza scrupoli deciso ad arricchirsi a scapito della salute del pianeta.<\/p>\n<p>Dopo \u201c<strong>The Whispered World<\/strong>\u201d, la <em>Daedalic<\/em> torna nel 2010 con un titolo giunto sul mercato dopo diversi anni di sviluppo (il primo annuncio risale al 2007 con il titolo di \u201c<em><strong>Earth: The Beginning<\/strong><\/em>\u201d). Una gestazione probabilmente travagliata che trascina con s\u00e9 i medesimi difetti tecnici del titolo precedente, come l\u2019aspect ratio di 4:3 in un mondo dominato da monitor wide, risoluzione bloccata e tanti, troppi bug legati all\u2019engine, con qualche crash e diversi glitch.<br \/>\nAncora una volta gli autori (questa volta capeggiati dal co-gamedesigner di \u201cThe Whispered World\u201d <em><strong>Jan M\u00fcller-Michaelis<\/strong><\/em> e da <em><strong>Kevin Mentz<\/strong><\/em>) optano per il look cartoon, in questo caso per\u00f2 applicato a personaggi umani e non di fantasia come invece avveniva nelle vicende di Sadwick. Il risultato \u00e8 estremamente bello da vedere quando la grafica \u00e8 ferma, ma in movimento vengono alla luce nuovamente le stesse imperfezioni del predecessore, come i pochi frame per le animazioni e i fondali poco \u2018vivi\u2019. Il sistema si rivela ancor meno adatto a rappresentare movenze umane, e il problema finisce per risaltare maggiormente.<!--more--><\/p>\n<div id=\"attachment_642\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/1.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-642\" decoding=\"async\" loading=\"lazy\" class=\" wp-image-642 \" title=\"ANB_1\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/1-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/1-300x187.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/1-1024x640.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/1.jpg 1440w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-642\" class=\"wp-caption-text\">La casa norvegese di Bent \u00e8 un calderone di rimpianti e tristezza.<\/p><\/div>\n<p>La scelta di non incidere troppo sul budget rappresentando le numerose cutscene con uno stile da comic animato sembra invece una buona soluzione, ma purtroppo tali sostituti ai classici video peccano non solo di ritmo (soprattutto a causa delle vignette che si innestano lentamente) ma anche di qualit\u00e0 generale (disegni non eccelsi, animazioni imbolsite). Il tempo si dilata anche per colpa di un\u2019interfaccia che avrebbe potuto facilmente essere pi\u00f9 snella, costringendo ogni volta a un paio di click superflui.<br \/>\nUna recitazione un po\u2019 monocorde dei personaggi, protagonisti inclusi, chiude il quadro tecnico, di certo non esaltante, di \u201c<strong>A New Beginning<\/strong>\u201d.<\/p>\n<div id=\"attachment_643\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/2.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-643\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-643 \" title=\"ANB_2\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/2-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/2-300x187.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/2-1024x640.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/2.jpg 1440w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-643\" class=\"wp-caption-text\">Tornando indietro nel tempo, Fay trova San Francisco completamente distrutta. Peccato non poterla esplorare.<\/p><\/div>\n<p>Passando alla sostanza vera e propria, la possibilit\u00e0 di poter girare liberamente in un mondo post-apocalittico viene invece subito smentita riducendo il tutto a una breve e solitaria sezione perlopi\u00f9 sotterranea che non riesce a essere evocativa o intrigante in nessun modo, complice anche una serie di enigmi un po\u2019 scriteriati che menano colpi pesanti alla fluidit\u00e0. Si rimpiangono un po\u2019 i tempi delle escursioni nel vecchio \u201c<strong>The Dig<\/strong>\u201d: il titolo della <em>Lucas<\/em> risultava infatti molto pi\u00f9 efficace nel rappresentare un mondo in sfacelo e la solitudine del protagonista a contatto con un ambiente alieno, potendo anche contare su un sonoro di fronte a cui quello di \u201cA New Beginning\u201d esce con le ossa rotte (pur contando su un paio di tracce musicali piuttosto buone).<\/p>\n<div id=\"attachment_646\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/3.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-646\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-646 \" title=\"ANB_3\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/3-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/3-300x187.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/3-1024x640.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/3.jpg 1440w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-646\" class=\"wp-caption-text\">Per un certo periodo Bent manifester\u00e0 una comprensibile diffidenza nei confronti del fantascientifico racconto di Fay.<\/p><\/div>\n<p>Quando l\u2019ambientazione passa ai giorni nostri e il ritmo continua a essere esageratamente compassato, \u201cA New Beginning\u201d sembra aver terminato le frecce al proprio arco. Un po\u2019 a sorpresa per\u00f2, durante la seconda parte, la storia di Bent e Fay cambia marcia proprio quando tutto sembrava perduto. Pur introducendo un <em>villain<\/em> piuttosto classico e streotipato, infatti, la sceneggiatura riesce a indovinare la strada giusta approfondendo efficacemente le relazioni fra i personaggi e adottando un ritmo pi\u00f9 incalzante, fino a un bel colpo di coda narrativo abbastanza imprevisto. Inoltre, i due protagonisti crescono col tempo, maturando un\u2019evoluzione ben sviluppata e coerente che provoca una sana empatia col giocatore, seppur un po\u2019 in ritardo. Il tutto riesce a far parzialmente assimilare le magagne riscontrate e un comparto enigmi che resta sempre poco riuscito, fra azioni praticamente automatiche e puzzle un po\u2019 avulsi dal contesto.<br \/>\nIn particolare, il rapporto padre-figlio fra Bent e Duve prende a un tratto una piega davvero interessante e realistica, grazie anche a un paio di battute molto ben piazzate e a qualche buon momento intimista, mostrando un\u2019anima (elemento gi\u00e0 riscontrato in \u201cThe Whispered World\u201d) che fino a quel momento era assente. Peccato per\u00f2 che tale storyline venga praticamente congelata proprio quando, forse, si avrebbe dovuto insistere di pi\u00f9.<\/p>\n<div id=\"attachment_647\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/4.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-647\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-647 \" title=\"ANB_4\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/4-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/4-300x187.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/4-1024x640.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/4.jpg 1440w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-647\" class=\"wp-caption-text\">La realizzazione delle cutscene in stile fumetto non \u00e8 eccezionale, ma a volte regala delle belle immagini.<\/p><\/div>\n<p>In compenso, viene presto portato all\u2019ebollizione il sottotesto della trama che riguarda la capacit\u00e0 o meno dell\u2019essere umano di reagire di fronte a una distruzione lenta ma inevitabile o, piuttosto, a una catastrofe imminente. L\u2019amaro finale del gioco intraprende una strada precisa ma lascia elegantemente posto a un\u2019ambiguit\u00e0 di fondo che spinge alla riflessione.<br \/>\nSi tratta di un risvolto un po\u2019 inaspettato, poich\u00e9 per gran parte del tempo l\u2019avventura si nasconde dietro un messaggio ambientalista piuttosto scontato: per fortuna, le carte vengono rimescolate nelle ultime ore &#8211; creando forse qualche forzatura \u2013 con una parte finale caratterizzata da un messaggio preciso che contiene un retrogusto assai pi\u00f9 indecifrabile.<\/p>\n<div id=\"attachment_648\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/5.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-648\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-648 \" title=\"ANB_5\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/5-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/5-300x187.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/5-1024x640.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/07\/5.jpg 1440w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-648\" class=\"wp-caption-text\">Uno degli enigmi pi\u00f9 forzati del gioco consiste nel ricalibrare dei flussi d&#39;acqua.<\/p><\/div>\n<p>\u201c<strong>A New Beginning<\/strong>\u201d \u00e8 un titolo figlio di una gestazione troppo lunga, costellato da tanti piccoli problemi tecnici e afflitto da troppi tempi morti. \u00c8 giusto per\u00f2 dare una chance ai bravi autori tedeschi, poich\u00e9 in \u201cA New Beginning\u201d sotto la scorza avventurosa batte un cuore. Debolmente, ma batte.<br \/>\n{rating}<\/p>\n<p><strong>La citazione<\/strong>:<br \/>\nOggy: La questione importante \u00e8 questa: come si pu\u00f2 spingere sette miliardi di persone ad agire? Due persone, da sole, non possono salvare il mondo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In un futuro devastato da una serie di catastrofi ecologiche, una squadra viene invitata indietro nel tempo per fermare lo scoppio di una centrale nucleare in Brasile, responsabile di una terribile reazione a catena che porter\u00e0 al disastro climatico. Ben presto l\u2019intera missione finisce per dipendere dalla giovane radio-operatrice Fay e da Bent Svensson, uno scienziato del passato che ha &hellip;<span class=\"more-link\"><a href=\"https:\/\/www.hexence.com\/gnupick\/a-new-beginning\/\"><span class=\"button\"><b>Continua a leggere &rarr;<\/b><\/span><\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/628"}],"collection":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/comments?post=628"}],"version-history":[{"count":25,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/628\/revisions"}],"predecessor-version":[{"id":657,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/628\/revisions\/657"}],"wp:attachment":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/media?parent=628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/categories?post=628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/tags?post=628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}