{"id":776,"date":"2012-08-29T13:07:40","date_gmt":"2012-08-29T11:07:40","guid":{"rendered":"http:\/\/www.hexence.com\/gnupick\/?p=776"},"modified":"2012-12-27T05:04:36","modified_gmt":"2012-12-27T04:04:36","slug":"innocent-until-caught","status":"publish","type":"post","link":"https:\/\/www.hexence.com\/gnupick\/innocent-until-caught\/","title":{"rendered":"Innocent Until Caught"},"content":{"rendered":"<p><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_0big.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-777\" title=\"IUC_cover\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_0big-235x300.jpg\" alt=\"\" width=\"235\" height=\"300\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_0big-235x300.jpg 235w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_0big.jpg 640w\" sizes=\"(max-width: 235px) 100vw, 235px\" \/><\/a>Il simpatico ladro Jack T. Ladd, durante un viaggio di routine con la sua nave spaziale rubata, viene beccato dal temutissimo fisco che gli impone di pagare tutti i suoi debiti: la condanna consiste in una lunghissima serie di torture, la morte e la vendita di organi (non necessariamente in quest\u2019ordine). Atterrato sulla luna di Tayte, Jack dovr\u00e0 rapidamente trovare un lavoro (poco importa se legale o meno) per saldare il seccante debito. Sulla sua strada, per\u00f2, trover\u00e0 approfittatori senza scrupoli, dittatori fanatici, sgraditi nuovi amici e perfino l\u2019amore.<\/p>\n<p>\u201c<strong>Innocent Until Caught<\/strong>\u201d \u00e8 un\u2019avventura sviluppata dalla <em>Divide by Zero<\/em> (con a capo <strong><em>Andy Blazdell<\/em><\/strong>) ed uscita sotto etichetta della gloriosa <em>Psygnosis<\/em> nel 1993.<br \/>\nL\u2019ambientazione \u00e8 futuristica e pesantemente sci-fi, mentre il tono \u00e8 irriverente\/demenziale &#8211; un mix molto raro nel mondo dei videogiochi, ma in questo caso si pu\u00f2 dire che sia grosso modo riuscito: a situazioni crude e talvolta anche violente (sulla sporca e malfamata Tayte regna la criminalit\u00e0) si contrappone un\u2019impostazione molto sopra le righe, con dialoghi sempre umoristici e numerose scenette comiche.<br \/>\nIl target di pubblico a cui si rivolge l\u2019avventura \u00e8, comunque, piuttosto adulto: frequenti appaiono infatti le allusioni e i riferimenti sessuali, che restano comunque nei limiti del buon gusto ma indirizzano lo humor verso uno stile pi\u00f9 \u2018da caserma\u2019 che pu\u00f2 essere fruito appieno dai pi\u00f9 maturi. Il protagonista, Jack, racchiude un po\u2019 tutte queste caratteristiche: \u00e8 un uomo che non guarda in faccia a nessuno, egoista e pronto a giocare sporco per arrivare al suo scopo, che sia l\u2019amore, il denaro o la semplice sopravvivenza. \u00c8 un tipo anche alquanto furbo e navigato, anche se, purtroppo per lui, molto sfortunato.<!--more--><\/p>\n<div id=\"attachment_778\" style=\"width: 310px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_1big.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-778\" decoding=\"async\" loading=\"lazy\" class=\" wp-image-778 \" title=\"IUC_1\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_1big-300x137.jpg\" alt=\"\" width=\"300\" height=\"137\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_1big-300x137.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_1big-1024x469.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_1big.jpg 1279w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-778\" class=\"wp-caption-text\">Il povero Jack \u00e8 stato catturato da &#39;quelli delle tasse&#39;. Perfino la loro navetta appare minacciosa...<\/p><\/div>\n<p>\u201cInnocent Until Caught\u201d presenta una trama frivola e non particolarmente intrigante. La sceneggiatura avvalora le prime impressioni, prendendo una piega un po\u2019 bizzarra solo dalla seconda met\u00e0 dell\u2019avventura, che innescher\u00e0 in noi il dubbio che sia stata improvvisata.<br \/>\nEppure\u2026 ci si diverte. I dialoghi fulminanti e la gustosissima simpatia dei personaggi bastano da soli a reggere il gioco, e ci si dimentica presto della debolezza della trama di fronte a righe che strappano inevitabilmente qualche risata (anche ad alta voce). Grande sar\u00e0 la curiosit\u00e0 di spulciare a fondo ogni dialogo ed esplorare anche la pi\u00f9 sfacciata delle provocazioni per godersi le buffe reazioni dei nostri interlocutori. Le varie gag, potenziate dal buon utilizzo delle animazioni, completano il quadro: a conti fatti, insomma, il divertimento non manca davvero.<br \/>\nParte del merito va alla comparsa di Narm, militare stupidotto influenzato dai film d\u2019azione pi\u00f9 stereotipati, destinato a divenire la \u2018spalla\u2019 dell\u2019eroe. La classica coppia drittone \/ ottuso funziona a meraviglia (da spanciarsi quando dovranno comporre la poesia d\u2019amore per Ruth) e dispiace davvero constatare che l\u2019elemento sia del tutto assente durante la prima parte del gioco.<\/p>\n<div id=\"attachment_779\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_2big.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-779\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-779 \" title=\"IUC_2\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_2big-300x186.jpg\" alt=\"\" width=\"300\" height=\"186\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_2big-300x186.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_2big-1024x636.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_2big.jpg 1279w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-779\" class=\"wp-caption-text\">Il banco dei pegni sar\u00e0 fondamentale nel corso delle nostre peripezie. Notare come la grafica del personaggio si adatti secondo l&#39;illuminazione del posto.<\/p><\/div>\n<p>Graficamente il livello \u00e8 buono. I fondali, che rendono bene l\u2019idea di un mondo fantascientifico, e le animazioni, poco fluide ma numerosissime (con tanto di rare espressioni facciali), risultano gradevoli e, soprattutto, funzionali alla narrazione e all\u2019umorismo; molto ben fatte le <em>cutscene<\/em> \u2018spaziali\u2019.<br \/>\nDavvero orecchiabile il principale tema musicale, che spicca di fronte a una serie di musichette midi appena carine ma davvero ripetitive. Gli effetti sonori, infine, sono insufficienti sia come qualit\u00e0 che come quantit\u00e0 (si contano sulle dita di una mano). L\u2019adattamento italiano dei testi, invece, \u00e8 un po\u2019 troppo \u2018libero\u2019, non particolarmente curato nel lessico n\u00e9 molto fedele all\u2019originale (anche se rende abbastanza bene l\u2019idea).<\/p>\n<p>Pesante l\u2019interfaccia, che fa uso di icone e di un inventario con un numero di slot limitato (davvero fastidioso e incomprensibile, considerando la mole di oggetti che ci si trova a trasportare): l\u2019aspetto peggiore, per\u00f2, \u00e8 che risulta molto imprecisa sia nel segnalare gli hot spots che nel cambiare \u2018verbo\u2019. Nel dettaglio, il tasto destro sar\u00e0 utilizzato per scorrere le icone ciclicamente (operazione molto lenta); in alternativa, si potr\u00e0 selezionare l\u2019icona giusta nel pannello in basso, ma non sempre il programma ricever\u00e0 il comando, costringendo a cliccare pi\u00f9 volte. Molto sgradevole, infine, l\u2019assenza di una descrizione degli oggetti segnalati sullo sfondo, attivabile in modo molto macchinoso cliccando sull\u2019icona \u2018occhio\u2019 e passando il cursore su essi (cos\u00ec come accadeva col verbo \u2018cos\u2019\u00e8\u2019 nei vecchi \u201c<strong>Maniac Mansion<\/strong>\u201d e \u201c<strong>Zak McKracken and the Alien Mindbenders<\/strong>\u201d).<\/p>\n<div id=\"attachment_781\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_3big.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-781\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-781 \" title=\"IUC_3\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_3big-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_3big-300x170.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_3big-1024x580.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_3big.jpg 1279w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-781\" class=\"wp-caption-text\">I dialoghi diretti verranno rappresentati in questo modo. Qui, Jack e Narm tentano di conquistare il cuore della bella Ruthie.<\/p><\/div>\n<p>Gli enigmi rappresentano un po\u2019 la\u00a0<em>summa<\/em> dei pregi e dei difetti di \u201cInnocent Until Caught\u201d. Basati quasi interamente su manipolazione di oggetti e dialoghi, i puzzle della prima parte del gioco compongono un mosaico abbastanza complesso e apprezzabile. Purtroppo, i programmatori \u2018barano\u2019 pi\u00f9 volte, utilizzando in varie occasioni l\u2019espediente del pixel hunting e costringendo il giocatore a un labirinto noioso e senza senso proprio a met\u00e0 dell\u2019avventura. Dopo ci\u00f2, e in seguito a un preciso cambio di rotta della storia, la curva di difficolt\u00e0 si abbassa notevolmente, con locazioni in numero minore e, soprattutto, pochissimi oggetti trasportabili. Il gioco continua ad accelerare di ritmo a ogni sezione e la sfida si fa sempre meno ardua fino ad arrivare alla semplice sequenza finale.<br \/>\nIl risultato globale presenta quindi un game design poco indovinato, che focalizza le vere difficolt\u00e0 solo all\u2019inizio, quando il giocatore deve ancora ambientarsi, per poi abbassare sostanzialmente il livello in seguito: sarebbe stato pi\u00f9 sensato il contrario.<\/p>\n<div id=\"attachment_782\" style=\"width: 310px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_9big.jpg\" target=\"_blank\"><img aria-describedby=\"caption-attachment-782\" decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-782 \" title=\"IUC_4\" src=\"http:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_9big-300x240.jpg\" alt=\"\" width=\"300\" height=\"240\" srcset=\"https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_9big-300x240.jpg 300w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_9big-1024x819.jpg 1024w, https:\/\/www.hexence.com\/gnupick\/wp-content\/uploads\/2012\/08\/Innocent-Until-Caught_9big.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-782\" class=\"wp-caption-text\">Durante la prima parte dell&#39;avventura, l&#39;inventario si riempir\u00e0 ben presto di ogni diavoleria. Un po&#39; dispersivo.<\/p><\/div>\n<p>\u201c<strong>Innocent Until Caught<\/strong>\u201d \u00e8 considerato un titolo un po\u2019 sottovalutato nel genere delle avventure grafiche. Mi sento in parte d\u2019accordo con questa affermazione, poich\u00e9 l\u2019intrattenimento puro \u00e8 decisamente presente e, pur nella sua leggerezza, il gioco \u00e8 assolutamente godibile. Purtroppo, una curva di difficolt\u00e0 mal calibrata, numerose frustrazioni qua e l\u00e0 e un aspetto tecnico poco curato gli hanno impedito di diventare il classico che forse avrebbe potuto essere.<br \/>\n{rating}<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>La citazione<\/strong><\/span>:<br \/>\nBrigadiere: Posso aiutarla, signore?<br \/>\nJack: Non mi prenderai mai vivo, sbirro!<br \/>\nBrigadiere: Perch\u00e9 dice questo?<br \/>\nJack: Sono un inguaribile bugiardo.<br \/>\nBrigadiere: Oh no! Un altro che vuole arruolarsi! Sparisca!<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\">Nota<\/span>: A quanto pare mi piacciono le sfide: \u201cInnocent Until Caught\u201d era una vera rogna fin dai tempi del DOS. Sui nuovi sistemi, naturalmente, i problemi per avviarlo correttamente si decuplicano. <a href=\"http:\/\/www.dosbox.com\/\">DOSBox<\/a> e D-Fend sono riusciti a compiere il miracolo, ma i settaggi sono un po\u2019 lunghetti. Innanzitutto, avrete \u2018necessariamente\u2019 bisogno dei vecchi driver DOS della Sound Blaster Pro 2 (in realt\u00e0 vanno bene anche quelli precedenti, ma bisogner\u00e0 adattare la configurazione), persi in qualche anfratto del sito della <a href=\"http:\/\/us.creative.com\/support\/downloads\/download.asp?DriverLang=1033&amp;searchString=SBP2DU.EXE&amp;Image1.x=16&amp;Image1.y=3\" target=\"_blank\">Creative Labs<\/a>. Il file che ci occorre \u00e8 chiamato CT-VOICE.DRV e andr\u00e0 piazzato nella cartella \u2018drv\u2019 all\u2019interno della dir del gioco stesso. In seguito, settate <a href=\"http:\/\/www.dosbox.com\/\">Dosbox<\/a> minuziosamente: scegliere \u2018sbpro2\u2019 come scheda audio, piazzate 16 mb di memoria, abilitate la memoria estesa (XMS), montate il disco \u2018c:\\\u2019 e inserite \u2018set sound=c:\\cartelladelgioco\u2019 nella sezione dell\u2019autoexec. Se siete fortunati, e fate partire prima il setup del gioco, dovreste poter godere sia delle musiche che, soprattutto, degli effetti sonori (rari e pessimi: bella fregatura!). In seguito, vantatevi pure con gli amici per essere riusciti a far girare al meglio un gioco problematico da configurare gi\u00e0 nel \u201993.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il simpatico ladro Jack T. Ladd, durante un viaggio di routine con la sua nave spaziale rubata, viene beccato dal temutissimo fisco che gli impone di pagare tutti i suoi debiti: la condanna consiste in una lunghissima serie di torture, la morte e la vendita di organi (non necessariamente in quest\u2019ordine). Atterrato sulla luna di Tayte, Jack dovr\u00e0 rapidamente trovare &hellip;<span class=\"more-link\"><a href=\"https:\/\/www.hexence.com\/gnupick\/innocent-until-caught\/\"><span class=\"button\"><b>Continua a leggere &rarr;<\/b><\/span><\/a><\/span><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/776"}],"collection":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/comments?post=776"}],"version-history":[{"count":7,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/776\/revisions"}],"predecessor-version":[{"id":1156,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/posts\/776\/revisions\/1156"}],"wp:attachment":[{"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/media?parent=776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/categories?post=776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hexence.com\/gnupick\/wp-json\/wp\/v2\/tags?post=776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}